{"id":324846,"date":"2021-02-02T13:32:39","date_gmt":"2021-02-02T12:32:39","guid":{"rendered":"https:\/\/www.bednar.com\/atlas-an_profi\/"},"modified":"2025-09-29T13:40:08","modified_gmt":"2025-09-29T11:40:08","slug":"atlas-an_profi","status":"publish","type":"produkt","link":"https:\/\/www.bednar.com\/fr\/atlas-an_profi\/","title":{"rendered":"ATLAS AN_PROFI D\u00e9chaumeur \u00e0 disques port\u00e9"},"excerpt":{"rendered":"<p>Un d\u00e9chaumeur \u00e0 disques port\u00e9, \u00e0 la structure robuste, proposant une largeur de 3 \u00e0 3,5 m\u00e8tres et con\u00e7u pour traiter d&rsquo;importantes quantit\u00e9s de r\u00e9sidus de moisson.<\/p>\n","protected":false},"featured_media":324848,"template":"","class_list":["post-324846","produkt","type-produkt","status-publish","has-post-thumbnail","hentry"],"acf":{"pozadovana_pracovni_operace":["podmitka"],"pozadovana_hloubka_zpracovani_pudy_min":"6","pozadovana_hloubka_zpracovani_pudy_min_imperial":"","pozadovana_hloubka_zpracovani_pudy_imperial_min":"","pozadovana_hloubka_zpracovani_pudy_max":"16","pozadovana_hloubka_zpracovani_pudy_max_imperial":"","pozadovana_hloubka_zpracovani_pudy_imperial_max":"","pozadovana_hloubka_zpracovani_pudy_hide":false,"pozadovany_pracovni_zaber_min":"3","pozadovany_pracovni_zaber_min_imperial":"","pozadovany_pracovni_zaber_imperial_min":"","pozadovany_pracovni_zaber_max":"3,5","pozadovany_pracovni_zaber_max_imperial":"","pozadovany_pracovni_zaber_imperial_max":"","pozadovany_pracovni_zaber_hide":false,"vykon_tazneho_prostredku_min":"150","vykon_tazneho_prostredku_max":"260","vykon_tazneho_prostredku_hide":false,"pozadovany_objem_zasobniku_min":"","pozadovany_objem_zasobniku_imperial_min":"","pozadovany_objem_zasobniku_max":"","pozadovany_objem_zasobniku_imperial_max":"","pozadovany_objem_zasobniku_hide":false,"ref_id":"C200061","item-bg":594327,"item-bg_kop\u00edrovat":false,"item-bg-mobile":false,"item-youtube":"https:\/\/www.youtube.com\/watch?v=cclNWgjic4U&feature=emb_logo","item-title":"","fixed-title":"ATLAS AN_PROFI","item-desc":"","item-mach-desc":"Un d\u00e9chaumeur \u00e0 disques port\u00e9 et robuste, con\u00e7u pour faire face \u00e0 d'importantes quantit\u00e9s de r\u00e9sidus","item-mach-config":"https:\/\/openconfigurator.bednar.com\/configurator\/15429043","item-mach-down":"https:\/\/www.bednar.com\/wp-content\/uploads\/prospekty\/fr\/atlas_an_profi-ao_profi-ae_profi_fr.pdf","item-mach-agro":"","item-align":true,"item-code":"","google-map":"","disable-header":false,"main-content":[{"acf_fc_layout":"section-fixed-submenu","h1-title":false},{"acf_fc_layout":"section-breadcrumbs"},{"acf_fc_layout":"section-title","item-title":"UN D\u00c9CHAUMEUR \u00c0 DISQUES PORT\u00c9 ET ROBUSTE","item-desc":"<p>La structure robuste du d\u00e9chaumeur \u00e0 disques port\u00e9 AN_PROFI et les grands disques d&rsquo;un diam\u00e8tre de 620 \u00d7 6 mm lui permettent de p\u00e9n\u00e9trer facilement le sol et d&rsquo;enfouir de grandes quantit\u00e9s de r\u00e9sidus. Le d\u00e9chaumeur \u00e0 disques port\u00e9 AN_PROFI est principalement con\u00e7u pour les petits agriculteurs qui souhaitent travailler leur sol \u00e0 une profondeur maximale de 16 centim\u00e8tres.<\/p>\n","item-mach-par":true},{"acf_fc_layout":"section-title-anchor","item-title":"Kl\u00ed\u010dov\u00e9 vlastnosti","item-desc":"<p>Un d\u00e9chaumeur \u00e0 disques robuste, de conception courte, con\u00e7u pour travailler le sol jusqu&rsquo;\u00e0 une profondeur de 16 centim\u00e8tres et pour enfouir de grandes quantit\u00e9s de r\u00e9sidus post-r\u00e9colte.<\/p>\n","disable-section":false},{"acf_fc_layout":"section-content","item-icon":false,"item-subtitle":"DISQUES D'UN GRAND DIAM\u00c8TRE DE 620 \u00d7 6 MM","item-title":"Une excellent d\u00e9coupe, un excellent m\u00e9lange et un excellent enfouissement de la mati\u00e8re.","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_aggresive_discs_diameter_cm_in-1.png","item-video-id":"","item-content":"<p>Le principal atout des d\u00e9chaumeurs \u00e0 disques ATLAS AN_PROFI r\u00e9side dans leur section de disques qui est \u00e9quip\u00e9e de grands disques de 620 \u00d7 6 mm de diam\u00e8tre. La fixation des diff\u00e9rents disques offre un guidage pr\u00e9cis et ind\u00e9pendant des disques pour un travail du profil du sol uniforme. La section de disques peut \u00eatre \u00e9quip\u00e9e de disques cr\u00e9nel\u00e9s ou de disques agressifs. Les disques agressifs ont une forme sp\u00e9cifique qui facilite leur p\u00e9n\u00e9tration dans le sol et ils ont avant tout un meilleur effet coupant et m\u00e9langeur.<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"item-button-class":"","tabs":false,"toggles":false,"gallery":false},{"acf_fc_layout":"section-content","item-icon":false,"item-subtitle":"UN EXCELLENT D\u00c9GAGEMENT","item-title":"Pour pouvoir enfouir d'importantes quantit\u00e9s de r\u00e9sidus, sans incident.","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_space_between_sections_frame_clearance-1.png","item-video-id":"","item-content":"<p>Les ch\u00e2ssis des mod\u00e8les ATLAS AN_PROFI ont un excellent d\u00e9gagement. De ce fait, ils sont capables de m\u00e9langer et d&rsquo;enfouir parfaitement de grandes quantit\u00e9s de mati\u00e8re organique, de r\u00e9sidus de r\u00e9colte et de cultures interm\u00e9diaires.<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"item-button-class":"","tabs":false,"toggles":false,"gallery":false},{"acf_fc_layout":"section-content","item-icon":false,"item-subtitle":"MASSES SUPPL\u00c9MENTAIRES","item-title":"Pour am\u00e9liorer la p\u00e9n\u00e9tration dans le sol et am\u00e9liorer le travail en p\u00e9riode de s\u00e9cheresse.","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_zavazi.png","item-video-id":"","item-content":"<p>Gr\u00e2ce \u00e0 un poids total de 3\u00a0350 kg et \u00e0 un ch\u00e2ssis robuste, il sera possible d&rsquo;installer des masses suppl\u00e9mentaires d&rsquo;une masse de 200 kg sur les mod\u00e8les AN_PROFI. Ce masses augmentent la pression exerc\u00e9e sur la section de disques et facilitent ainsi sa p\u00e9n\u00e9tration, qui peut \u00eatre probl\u00e9matique en p\u00e9riode de s\u00e9cheresse.<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"item-button-class":"","tabs":false,"toggles":false,"gallery":false},{"acf_fc_layout":"section-content","item-icon":false,"item-subtitle":"UN R\u00c9GLAGE HYDRAULIQUE","item-title":"Pour r\u00e9gler facilement la profondeur de travail.","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_profi_hydraulicke_nastaveni_pracovni_hloubky.png","item-video-id":"","item-content":"<p>Le r\u00e9glage de la profondeur de travail est simple et confortable. il se r\u00e9alise \u00e0 l&rsquo;aide des hydroclips qui se basculent sur les v\u00e9rins des rouleaux arri\u00e8res.<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"item-button-class":"","tabs":false,"toggles":false,"gallery":false},{"acf_fc_layout":"section-content","item-icon":false,"item-subtitle":"DES DISQUES LAT\u00c9RAUX REPLIABLES","item-title":"Pour une plus grande largeur de travail et un transport en toute s\u00e9curit\u00e9.","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_sklopny_bocni_disk.png","item-video-id":"","item-content":"<p>Pour que le transport se d\u00e9roule en toute s\u00e9curit\u00e9, les disques lat\u00e9raux se replient vers le haut. Les disques pourront \u00eatre repli\u00e9s m\u00e9caniquement ou hydrauliquement tout en restant dans la cabine du tracteur. Si vous vous d\u00e9placez souvent sur les routes, nous vous recommandons d&rsquo;opter pour la solution hydraulique. En d\u00e9ployant les disques lat\u00e9raux pour les placer dans leur position de travail, vous utiliserez l&rsquo;int\u00e9gralit\u00e9 de la largeur de la machine, soit 3 m\u00e8tres.<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"item-button-class":"","tabs":false,"toggles":false,"gallery":false},{"acf_fc_layout":"section-cta-box"},{"acf_fc_layout":"section-title-anchor","item-title":"Popis stroje","item-desc":"<p>Les principaux \u00e9l\u00e9ments du d\u00e9chaumeur \u00e0 disques, en bref.<\/p>\n","disable-section":false},{"acf_fc_layout":"section-3d-model","item-3d-images":"https:\/\/www.bednar.com\/wp-content\/uploads\/3D\/ATLAS-AN-PROFI\/ATLAS_AN_3000_PROFI_360","model-right":false,"item-main-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_zakladni.jpg","item-list":[{"item-pos":"71.7695%,14.3541%","item-pos-img":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_3_bodovy_zaves.jpg","item-name":"Attelage trois points","item-desc":"<p>Un raccordement simple \u00e0 l&rsquo;attelage trois points du tracteur. Attelage de cat\u00e9gorie II\/III.<\/p>\n"},{"item-pos":"51.8436%,28.5144%","item-pos-img":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_pracovni_hloubka.jpg","item-name":"R\u00e9glage de la profondeur de travail","item-desc":"<p>Un r\u00e9glage hydraulique et confortable de la profondeur de travail, sans devoir quitter la cabine du tracteur.<\/p>\n"},{"item-pos":"78.0523%,62.6359%","item-pos-img":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_diskova_sekce.jpg","item-name":"Section de disques","item-desc":"<p>Une section de disques \u00e9quip\u00e9e de disques cr\u00e9nel\u00e9s ou  agressifs, de 620 \u00d7 6 mm de diam\u00e8tre et munis d&rsquo;une protection AUTO-RESET \u00e0 ressort.<\/p>\n"},{"item-pos":"53.4042%,32.6229%","item-pos-img":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_robustni_ram.jpg","item-name":"Ch\u00e2ssis robuste","item-desc":"<p>Il vous garantit un excellent d\u00e9gagement pour les conditions difficiles et permet d&rsquo;y installer des masses suppl\u00e9mentaires.<\/p>\n"},{"item-pos":"67.2046%,19.8737%","item-pos-img":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_zavazi.jpg","item-name":"Masses suppl\u00e9mentaires","item-desc":"<p>Elles contraignent le ch\u00e2ssis de la machine et facilitent la p\u00e9n\u00e9tration des disques dans le sol.<\/p>\n"},{"item-pos":"31.4142%,60.0261%","item-pos-img":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/atlas_an_3000_profi_pech.jpg","item-name":"Rouleaux arri\u00e8re","item-desc":"<p>Ils replombent et referment le profil du sol pour que la lev\u00e9e de la future culture soit uniforme et que l&rsquo;\u00e9vaporation de l&rsquo;humidit\u00e9 du sol soit minimale.<\/p>\n"}]},{"acf_fc_layout":"section-inov-tech","inov-tech-ids":[{"ID":321414,"post_author":"3","post_date":"2021-02-02 14:38:22","post_date_gmt":"2021-02-02 13:38:22","post_content":"","post_title":"MAINTENANCE-FREE BEARING DESIGN","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"maintenance-free-bearing-design","to_ping":"","pinged":"","post_modified":"2021-03-31 09:31:56","post_modified_gmt":"2021-03-31 07:31:56","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.bednar.com\/technologie\/bezudrzbove-reseni-lozisek\/","menu_order":0,"post_type":"technologie","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":321415,"post_author":"3","post_date":"2021-02-02 14:37:42","post_date_gmt":"2021-02-02 13:37:42","post_content":"","post_title":"FLEXI-BOX MOUNTING OF ARMS TO THE FRAME","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"flexi-box-mounting-of-tines-to-the-frame","to_ping":"","pinged":"","post_modified":"2024-01-30 14:35:51","post_modified_gmt":"2024-01-30 13:35:51","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.bednar.com\/technologie\/flexi-box-uchyceni-slupic-k-ramu\/","menu_order":0,"post_type":"technologie","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":321416,"post_author":"3","post_date":"2021-02-02 14:37:07","post_date_gmt":"2021-02-02 13:37:07","post_content":"","post_title":"HORIZONTAL AUTO-RESET ARMS PROTECTION (AN_PROFI)","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"horizontal-non-stop-tine-protection-an-profi","to_ping":"","pinged":"","post_modified":"2024-01-30 14:37:37","post_modified_gmt":"2024-01-30 13:37:37","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.bednar.com\/technologie\/horizontalni-non-stop-jisteni-slupice-an-profi\/","menu_order":0,"post_type":"technologie","post_mime_type":"","comment_count":"0","filter":"raw"}]},{"acf_fc_layout":"section-content-full-without","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/nahledove\/web_what_says_farmers_background-1.jpg","item-photo-left":"https:\/\/www.bednar.com\/wp-content\/uploads\/produkty\/atlas-an_profi\/eta-selva-patrick_img_9184.jpg","item-content-grey":"<h3>QU&rsquo;EN DISENT LES AGRICULTEURS ?<\/h3>\n<p>\u00ab\u00a0Nous avons achet\u00e9 un d\u00e9chaumeur ATLAS AN_PROFI pour remplacer notre ancien d\u00e9chaumeur \u00e0 disques. Ce qui nous a convaincu, ce sont les disques de 620 mm de diam\u00e8tre, la protection par ressort, mais aussi et surtout le repli hydraulique des disques lat\u00e9raux et le r\u00e9glage hydraulique de la profondeur de travail. Avec ce petit d\u00e9chaumeur, nous ne devons plus sortir de la cabine de notre tracteur.\u00a0\u00bb<\/p>\n<p>Eta Selvia Patrick,<br \/>\nFrance<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"disable-section":false},{"acf_fc_layout":"section-title-anchor","item-title":"P\u0159\u00edslu\u0161enstv\u00ed","item-desc":"<p>Nous sommes parfaitement conscients que chaque client souhaite \u00e9quiper sa machine diff\u00e9remment et que chacun d\u2019entre eux envisage de l\u2019utiliser d\u2019une mani\u00e8re sp\u00e9cifique. C\u2019est la raison pour laquelle nous vous permettons d\u2019adapter votre d\u00e9chaumeur \u00e0 disques ATLAS AN_PROFI pour qu\u2019il r\u00e9ponde pr\u00e9cis\u00e9ment \u00e0 vos attentes.<\/p>\n","disable-section":false},{"acf_fc_layout":"section-accessories","acces-ids":[322927,322923,322889,322887,322871,322704,322863]},{"acf_fc_layout":"section-content-full"},{"acf_fc_layout":"section-content-full-without","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/nahledove\/bednar-agronomy.jpg","item-photo-left":false,"item-content-grey":"<h3 style=\"text-align: center;\">CONSEILLER AGRONOMIQUE<\/h3>\n<p style=\"text-align: center;\"><strong>LE D\u00c9CHAUMAGE<\/strong><br \/>\nEffectuer un d\u00e9chaumage rapide et de qualit\u00e9 est consid\u00e9r\u00e9 comme \u00e9tant l\u2019une des plus importantes op\u00e9rations de travail du sol. Pour d\u2019excellents r\u00e9sultats agronomiques, ce d\u00e9chaumage doit \u00eatre r\u00e9alis\u00e9 le plus rapidement possible, apr\u00e8s la r\u00e9colte. Il garantit une bonne gestion de l\u2019humidit\u00e9 du sol et une lev\u00e9e rapide des adventices, limitant leur prolif\u00e9ration dans vos champs.<\/p>\n","item-button":"","item-button-url":"","item-button-url-int":false,"disable-section":false},{"acf_fc_layout":"section-title-anchor","item-title":"Technick\u00e1 data","item-desc":"","disable-section":false},{"acf_fc_layout":"section-table","table":{"use_header":true,"header":[{"c":"ATLAS AN_PROFI"},{"c":""},{"c":"AN 3000 PROFI\n"},{"c":"AN 3500 PROFI\n"}],"caption":false,"body":[[{"c":"Pracovn\u00ed \u0161\u00ed\u0159ka"},{"c":"m"},{"c":"3"},{"c":"3,5"}],[{"c":"P\u0159epravn\u00ed \u0161\u00ed\u0159ka"},{"c":"m"},{"c":"3"},{"c":"3,5"}],[{"c":"P\u0159epravn\u00ed d\u00e9lka"},{"c":"m"},{"c":"3,3\n"},{"c":"3,3"}],[{"c":"P\u0159epravn\u00ed v\u00fd\u0161ka"},{"c":"m"},{"c":"1,8\n"},{"c":"1,8\n"}],[{"c":"Po\u010det disk\u016f"},{"c":"ks"},{"c":"24\n"},{"c":"28\n"}],[{"c":"Pracovn\u00ed hloubka disk\u016f*"},{"c":"cm"},{"c":"6 - 16"},{"c":"6 - 16"}],[{"c":"Pracovn\u00ed \u00fahel disk\u016f"},{"c":"\u00b0"},{"c":"p\u0159edn\u00ed 18 \/ zadn\u00ed 15"},{"c":"p\u0159edn\u00ed 18 \/ zadn\u00ed 15"}],[{"c":"Pr\u016fm\u011br disk\u016f"},{"c":"mm"},{"c":"620"},{"c":"620"}],[{"c":"Tlou\u0161\u0165ka disku"},{"c":"mm"},{"c":"6\n"},{"c":"6\n"}],[{"c":"Typ ji\u0161t\u011bn\u00ed disk\u016f"},{"c":""},{"c":"individu\u00e1ln\u00ed pru\u017einov\u00e9"},{"c":"individu\u00e1ln\u00ed pru\u017einov\u00e9"}],[{"c":"Rozte\u010d disk\u016f"},{"c":"cm"},{"c":"25"},{"c":"25\n"}],[{"c":"Vzd\u00e1lenost mezi dv\u011bma \u0159adami disk\u016f"},{"c":"cm"},{"c":"110"},{"c":"110\n"}],[{"c":"Sv\u011btlost r\u00e1mu"},{"c":"cm"},{"c":"70\n"},{"c":"70\n"}],[{"c":"Doporu\u010den\u00fd v\u00fdkon*"},{"c":"hp"},{"c":"150 - 240"},{"c":"170 - 260"}],[{"c":"Typ r\u00e1mu"},{"c":""},{"c":"pevn\u00fd"},{"c":"pevn\u00fd"}],[{"c":"Max. celkov\u00e1 hmotnost**"},{"c":"kg"},{"c":"2 800"},{"c":"3 350"}]]},"table-imp":false,"table-info":"<p>*D\u00e9pend des conditions d&rsquo;utilisation **En fonction des \u00e9quipements de la machine<br \/>\n<br \/>\n<em>Chez BEDNAR, nous nous effor\u00e7ons en permanence de maintenir les informations de ce site web exactes, \u00e0 jour et utiles. Dans le but d\u2019am\u00e9liorer votre exp\u00e9rience et d\u2019optimiser les performances agricoles, certaines sp\u00e9cifications peuvent \u00eatre modifi\u00e9es par rapport \u00e0 ce qui est actuellement pr\u00e9sent\u00e9. Les sp\u00e9cifications techniques compl\u00e8tes seront confirm\u00e9es par votre repr\u00e9sentant BEDNAR agr\u00e9\u00e9 au moment de la commande.<\/em><\/p>\n","table-button-url":"https:\/\/www.bednar.com\/wp-content\/uploads\/opotrebitelne-nd\/fr\/atlas_an_ao_fr.pdf","table-max-width":false,"konfigurator-nd":false},{"acf_fc_layout":"section-title-anchor","item-title":"Galerie \/ M\u00e9dia","item-desc":"","disable-section":false},{"acf_fc_layout":"section-gallery","videos":[{"item-id":"https:\/\/www.youtube.com\/embed\/cclNWgjic4U"},{"item-id":"https:\/\/www.youtube.com\/embed\/IAgf_PJAqU4"}],"photos":[{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","title":"ATLAS AN_PROFI","filename":"AN-3000_MG_2801.jpg","filesize":249936,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/an-3000_mg_2801-2\/","alt":"","author":"3","description":"","caption":"","name":"an-3000_mg_2801-2","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:16","modified":"2021-02-02 14:08:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/AN-3000_MG_2801.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}},{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","title":"ATLAS AN_PROFI","filename":"Atlas_AN3000_MG_2843.jpg","filesize":276565,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/atlas_an3000_mg_2843-2\/","alt":"","author":"3","description":"","caption":"","name":"atlas_an3000_mg_2843-2","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:20","modified":"2021-02-02 14:08:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2843.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}},{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","title":"ATLAS AN_PROFI","filename":"Atlas_AN3000_MG_2861.jpg","filesize":302735,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/atlas_an3000_mg_2861-2\/","alt":"","author":"3","description":"","caption":"","name":"atlas_an3000_mg_2861-2","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:13","modified":"2021-02-02 14:08:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2861.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}},{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","title":"ATLAS AN_PROFI","filename":"Atlas_AN3000_MG_2854_NEB.jpg","filesize":257858,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/atlas_an3000_mg_2854_neb-3\/","alt":"","author":"3","description":"","caption":"","name":"atlas_an3000_mg_2854_neb-3","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:21","modified":"2021-02-02 14:08:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2854_NEB.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}},{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","title":"ATLAS AN_PROFI","filename":"Atlas_AN3000_MG_2829.jpg","filesize":314152,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/atlas_an3000_mg_2829-2\/","alt":"","author":"3","description":"","caption":"","name":"atlas_an3000_mg_2829-2","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:19","modified":"2021-02-02 14:08:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2829.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}},{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","title":"ATLAS AN_PROFI","filename":"Atlas_AN3000_MG_2592.jpg","filesize":218115,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/atlas_an3000_mg_2592-2\/","alt":"","author":"3","description":"","caption":"","name":"atlas_an3000_mg_2592-2","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:17","modified":"2021-02-02 14:08:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_2592.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}},{"ID":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","id":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","title":"ATLAS AN_PROFI","filename":"Atlas_AN3000_MG_6780.jpg","filesize":241548,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","link":"https:\/\/www.bednar.com\/en\/atlas-an_profi\/atlas_an3000_mg_6780-2\/","alt":"","author":"3","description":"","caption":"","name":"atlas_an3000_mg_6780-2","status":"inherit","uploaded_to":321270,"date":"2021-02-02 14:08:15","modified":"2021-02-02 14:08:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","medium-width":1,"medium-height":1,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","large-width":1,"large-height":1,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","2048x2048-width":1,"2048x2048-height":1,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","header-thumb-width":1,"header-thumb-height":1,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","section-thumb-width":1,"section-thumb-height":1,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","news-thumb-width":1,"news-thumb-height":1,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/2021\/02\/Atlas_AN3000_MG_6780.jpg","wpcf7-post-image-width":1,"wpcf7-post-image-height":1}}]},{"acf_fc_layout":"section-title-anchor","item-title":"Reference a zku\u0161enosti","item-desc":"","disable-section":false},{"acf_fc_layout":"section-news-slider","cat-id":false,"post-id":false,"disable-slider":false,"slider-count8":false,"slider-noautoplay":false,"disable-section":false},{"acf_fc_layout":"section-title","item-title":"TYPOV\u011a P\u0158\u00cdBUZN\u00c9 KATEGORIE","item-desc":"","item-mach-par":false},{"acf_fc_layout":"section-related","page-ids":[324840,324824]},{"acf_fc_layout":"section-title","item-title":"KONTAKTN\u00cd FORMUL\u00c1\u0158","item-desc":"<p>Pot\u0159ebujete poradit s v\u00fdb\u011brem, m\u00e1te z\u00e1jem o p\u0159edv\u00e1d\u011bn\u00ed stroje? Kontaktujte n\u00e1s!<\/p>\n","item-mach-par":false},{"acf_fc_layout":"section-contact-form","contact-form":null}],"nav-main-cat":322265,"nav-main-cat_kop\u00edrovat":false,"nav-sub-cat":323145,"_aviaLayoutBuilderCleanData":"","page-type":"other","pageGroup":"","post-new-website":false,"pozadovana_hloubka_zpracovani_pudy_icon":"https:\/\/www.bednar.com\/wp-content\/themes\/bednar.com\/img\/icon-hlouka-zaberu.svg","pozadovany_pracovni_zaber_icon":"https:\/\/www.bednar.com\/wp-content\/themes\/bednar.com\/img\/icon-sirka-zaberu.svg","vykon_tazneho_prostredku_icon":"https:\/\/www.bednar.com\/wp-content\/themes\/bednar.com\/img\/icon-vykon-prostredku.svg","pozadovany_objem_zasobniku_icon":"https:\/\/www.bednar.com\/wp-content\/themes\/bednar.com\/img\/icon-objem-zasobniku.svg"},"_links":{"self":[{"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/produkt\/324846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":3,"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/produkt\/324846\/revisions"}],"predecessor-version":[{"id":630381,"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/produkt\/324846\/revisions\/630381"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/pages\/323145"},{"embeddable":true,"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/pages\/322265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/media\/324848"}],"wp:attachment":[{"href":"https:\/\/www.bednar.com\/en\/wp-json\/wp\/v2\/media?parent=324846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}