{"id":603465,"date":"2025-03-27T07:00:24","date_gmt":"2025-03-27T06:00:24","guid":{"rendered":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-novinka-mezi-diskovymi-podmitaci-bednar\/"},"modified":"2025-04-08T15:06:58","modified_gmt":"2025-04-08T13:06:58","slug":"atlas-ae_l-novinka-mezi-diskovymi-podmitaci-bednar","status":"publish","type":"post","link":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-une-nouveaute-parmi-les-dechaumeurs-a-disques-bednar\/","title":{"rendered":"ATLAS AE_L : une nouveaut\u00e9 parmi les d\u00e9chaumeurs \u00e0 disques BEDNAR"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>BEDNAR lance un nouveau mod\u00e8le de d\u00e9chaumeurs \u00e0 disques appel\u00e9 ATLAS AE_L. Comme son nom l&rsquo;indique, il s&rsquo;agit d&rsquo;un d\u00e9chaulmeur avec un grand diam\u00e8tre de disque de 620 mm. Cependant, le d\u00e9chaumeur \u00e0 disque ATLAS AE_L reprend un certain nombre de caract\u00e9ristiques techniques qui \u00e9taient auparavant les points forts de la s\u00e9rie de mod\u00e8les SWIFTERDISC.<\/p>\n","protected":false},"author":14,"featured_media":603398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79,543,820,1924],"tags":[],"class_list":["post-603465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-a-propos-de-nous","category-de-notre-part","category-atlas-ae_l-fr"],"acf":{"item-bg":false,"item-bg_kop\u00edrovat":false,"item-bg-mobile":false,"item-youtube":"","item-title":"","fixed-title":"","item-desc":"","item-mach-desc":"","item-mach-config":"","item-mach-down":"","item-align":false,"item-code":"","google-map":"","disable-header":false,"main-content":[{"acf_fc_layout":"section-news-cols","item-cols":[{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1.jpg","item-content":"<p>Un nouveau mod\u00e8le dans la gamme des d\u00e9chaumeurs \u00e0 disques : l&rsquo;ATLAS AE 12400 L avec une largeur de travail de 12,4 m<\/p>\n","item-photo-align":false,"item-content-color":false}]},{"acf_fc_layout":"section-news-title","item-title":"Ch\u00e2ssis lat\u00e9raux repliables - conception \u00e9prouv\u00e9e depuis 2008","item-content":"<p>Le d\u00e9chaumeur \u00e0 disques  ATLAS AE 12400 L conserve le concept typique des mod\u00e8les \u00ab\u00a0E\u00a0\u00bb. Il s&rsquo;agit d&rsquo;un ch\u00e2ssis principal avec un essieu de transport avant et deux ch\u00e2ssis lat\u00e9raux repliables. L&rsquo;avantage est le repliage rapide en position de transport, sans d\u00e9passer la largeur de transport autoris\u00e9e (3 m) et la hauteur de la machine (4 m). La conception de la machine r\u00e9duit le nombre de v\u00e9rins hydrauliques o\u00f9 la pression pourrait \u00eatre perdue sur les ch\u00e2ssis lat\u00e9raux (ce qui contribue \u00e9galement au faible nombre de points de lubrification).<\/p>\n"},{"acf_fc_layout":"section-news-cols","item-cols":[{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","item-content":"<p>BEDNAR utilise le concept des deux ch\u00e2ssis lat\u00e9raux sur les machines \u00e0 grande capacit\u00e9 depuis 2008.<\/p>\n","item-photo-align":false,"item-content-color":false},{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","item-content":"<p>ATLAS AE_L r\u00e9pond aux conditions de transport suivantes : largeur max. 3 m, hauteur max. 4 m<\/p>\n","item-photo-align":false,"item-content-color":false}]},{"acf_fc_layout":"section-news-title","item-title":"TWIN-DISC et X-PRECISE - toujours sur la bonne voie","item-content":"<p>La section des disques est \u00e9quip\u00e9e de disques de 620 mm de diam\u00e8tre et de 6 mm d&rsquo;\u00e9paisseur. La principale nouveaut\u00e9 du mod\u00e8le ATLAS AE_L est la m\u00e9thode de montage des disques, qui est con\u00e7ue avec le syst\u00e8me TWIN-DISC (un bras, deux disques). Le syst\u00e8me TWIN-DISC contribue \u00e0 doubler l&rsquo;espace de fixation des segments de caoutchouc par rapport \u00e0 un montage d&rsquo;un seul disque sur un seul bras. Cette solution technique augmente consid\u00e9rablement le rendement de la machine lors du traitement de grandes quantit\u00e9s de r\u00e9sidus post-r\u00e9colte.<\/p>\n"},{"acf_fc_layout":"section-news-cols","item-cols":[{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2.jpg","item-content":"<p>La disposition en X des sections de disques (syst\u00e8me X-PRECISE) emp\u00eache la machine de d\u00e9river lat\u00e9ralement sur les terrains en pente.<\/p>\n","item-photo-align":false,"item-content-color":false}]},{"acf_fc_layout":"section-news-title","item-title":"","item-content":"<p>Les mod\u00e8les ATLAS AE_L ont des sections de disque dispos\u00e9es en forme de \u00ab\u00a0X\u00a0\u00bb. La partie centrale de la section des disques est \u00e9quip\u00e9e d&rsquo;un seul disque. Cette solution technique innovante \u00e9limine le mouvement lat\u00e9ral de la machine, appel\u00e9 d\u00e9rive, m\u00eame en cas de travail sur des pentes ou des terrains accident\u00e9s.<\/p>\n"},{"acf_fc_layout":"section-news-title","item-title":"Tourner en bout de champ - rapidement et sans all\u00e9ger le tracteur","item-content":"<p>Seule la section du disque est excav\u00e9e lors du virage en bout de champ et la machine est soutenue par les roues de transport, les roues de support et les rouleaux arri\u00e8re. Cette solution \u00e9limine la charge n\u00e9gative sur l&rsquo;attelage et la l\u00e9g\u00e8ret\u00e9 du tracteur en position de demi-tour de la machine et contribue de mani\u00e8re significative \u00e0 l&rsquo;acc\u00e9l\u00e9ration du demi-tour.<\/p>\n"},{"acf_fc_layout":"section-news-title","item-title":"Nouvelle solution de conception - pour un terrain parfait","item-content":"<p>Une solution technique int\u00e9ressante est la section en X au centre de la machine devant les rouleaux arri\u00e8re et la disposition asym\u00e9trique des rouleaux arri\u00e8re. La section en X dans la partie centrale de la machine aplanit la surface et emp\u00eache la formation d&rsquo;une cr\u00eate centrale. La conception asym\u00e9trique du rouleau arri\u00e8re aplanit la surface dans la partie centrale de la machine dans une tr\u00e8s large mesure. Il existe diff\u00e9rents mod\u00e8les de rouleaux simples \u00e0 l&rsquo;arri\u00e8re, qui sont toujours \u00e9quip\u00e9es de raclettes.<\/p>\n"},{"acf_fc_layout":"section-news-cols","item-cols":[{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3.jpg","item-content":"<p>La conception asym\u00e9trique du rouleau arri\u00e8re, combin\u00e9e \u00e0 la section en X au centre de la machine, contribue \u00e0 une parcelle plane sur toute la largeur de travail.<\/p>\n","item-photo-align":false,"item-content-color":false}]},{"acf_fc_layout":"section-news-title","item-title":"R\u00e9glage hydraulique de la profondeur de travail - \u00e9quipement de base","item-content":"<p>Le r\u00e9glage de la profondeur de travail de la machine est tr\u00e8s facile. L&rsquo;ATLAS AE_L est \u00e9quip\u00e9 de s\u00e9rie d&rsquo;un r\u00e9glage hydraulique de la profondeur de travail, qui s&rsquo;effectue en ins\u00e9rant le nombre requis d&rsquo;hydroclips int\u00e9gr\u00e9s sur les rouleaux arri\u00e8re, les roues de support et l&rsquo;essieu de transport.<\/p>\n<p>Gr\u00e2ce \u00e0 son grand diam\u00e8tre de disque, le cultivateur \u00e0 disques ATLAS AE_L est particuli\u00e8rement adapt\u00e9 \u00e0 l&rsquo;incorporation et au m\u00e9lange des r\u00e9sidus post-r\u00e9colte de tournesol, de ma\u00efs ou de colza d&rsquo;hiver.<\/p>\n"},{"acf_fc_layout":"sections-buttons-list","sections-buttons-title":false,"item-title":"","buttons":[{"item-button-name":"Plus d'informations sur le d\u00e9chaumeurs \u00e0 disques  ATLAS AE_L","item-button-url":"","item-button-url-int":592700,"item-button-icon":false,"item-button-target":false,"item-button-scroll":false}]},{"acf_fc_layout":"section-news-title","item-title":"","item-content":"<p style=\"text-align: right;\">JOY OF FARMING<br \/>\n<a href=\"mailto:marketing@bednar.com\" target=\"_blank\" rel=\"noopener\">marketing@bednar.com<\/a><br \/>\nBEDNAR FMT s.r.o.<\/p>\n"},{"acf_fc_layout":"section-gallery","videos":false,"photos":[{"ID":603452,"id":603452,"title":"ATLAS AE_L new implement in BEDNAR portfolio (1)","filename":"atlas-ae_l-new-implement-in-bednar-portfolio-1.jpg","filesize":108682,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1.jpg","link":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-une-nouveaute-parmi-les-dechaumeurs-a-disques-bednar\/atlas-ae_l-new-implement-in-bednar-portfolio-1-2\/","alt":"","author":"14","description":"","caption":"","name":"atlas-ae_l-new-implement-in-bednar-portfolio-1-2","status":"inherit","uploaded_to":603465,"date":"2025-03-26 13:42:05","modified":"2025-03-26 13:42:05","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":1030,"height":500,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-280x185.jpg","thumbnail-width":280,"thumbnail-height":185,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-768x373.jpg","medium_large-width":768,"medium_large-height":373,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-1024x497.jpg","large-width":1024,"large-height":497,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1.jpg","1536x1536-width":1030,"1536x1536-height":500,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1.jpg","2048x2048-width":1030,"2048x2048-height":500,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1.jpg","header-thumb-width":1030,"header-thumb-height":500,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-860x480.jpg","section-thumb-width":860,"section-thumb-height":480,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-390x315.jpg","news-thumb-width":390,"news-thumb-height":315,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-1-80x80.jpg","wpcf7-post-image-width":80,"wpcf7-post-image-height":80}},{"ID":603398,"id":603398,"title":"ATLAS AE_L new implement in BEDNAR portfolio (4)","filename":"atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","filesize":147168,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","link":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-une-nouveaute-parmi-les-dechaumeurs-a-disques-bednar\/atlas-ae_l-new-implement-in-bednar-portfolio-4-2\/","alt":"","author":"14","description":"","caption":"","name":"atlas-ae_l-new-implement-in-bednar-portfolio-4-2","status":"inherit","uploaded_to":603465,"date":"2025-03-26 13:41:52","modified":"2025-03-26 13:41:52","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":800,"height":533,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4-280x185.jpg","thumbnail-width":280,"thumbnail-height":185,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","large-width":800,"large-height":533,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","1536x1536-width":800,"1536x1536-height":533,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","2048x2048-width":800,"2048x2048-height":533,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4.jpg","header-thumb-width":800,"header-thumb-height":533,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4-800x480.jpg","section-thumb-width":800,"section-thumb-height":480,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4-390x315.jpg","news-thumb-width":390,"news-thumb-height":315,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-4-80x80.jpg","wpcf7-post-image-width":80,"wpcf7-post-image-height":80}},{"ID":603380,"id":603380,"title":"ATLAS AE_L new implement in BEDNAR portfolio (5)","filename":"atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","filesize":117058,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","link":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-une-nouveaute-parmi-les-dechaumeurs-a-disques-bednar\/atlas-ae_l-new-implement-in-bednar-portfolio-5-2\/","alt":"","author":"14","description":"","caption":"","name":"atlas-ae_l-new-implement-in-bednar-portfolio-5-2","status":"inherit","uploaded_to":603465,"date":"2025-03-26 13:41:47","modified":"2025-03-26 13:41:47","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":800,"height":533,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5-280x185.jpg","thumbnail-width":280,"thumbnail-height":185,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","large-width":800,"large-height":533,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","1536x1536-width":800,"1536x1536-height":533,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","2048x2048-width":800,"2048x2048-height":533,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5.jpg","header-thumb-width":800,"header-thumb-height":533,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5-800x480.jpg","section-thumb-width":800,"section-thumb-height":480,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5-390x315.jpg","news-thumb-width":390,"news-thumb-height":315,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-5-80x80.jpg","wpcf7-post-image-width":80,"wpcf7-post-image-height":80}},{"ID":603416,"id":603416,"title":"ATLAS AE_L new implement in BEDNAR portfolio (2)","filename":"atlas-ae_l-new-implement-in-bednar-portfolio-2.jpg","filesize":78056,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2.jpg","link":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-une-nouveaute-parmi-les-dechaumeurs-a-disques-bednar\/atlas-ae_l-new-implement-in-bednar-portfolio-2-2\/","alt":"","author":"14","description":"","caption":"","name":"atlas-ae_l-new-implement-in-bednar-portfolio-2-2","status":"inherit","uploaded_to":603465,"date":"2025-03-26 13:41:57","modified":"2025-03-26 13:41:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":1030,"height":500,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-280x185.jpg","thumbnail-width":280,"thumbnail-height":185,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-768x373.jpg","medium_large-width":768,"medium_large-height":373,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-1024x497.jpg","large-width":1024,"large-height":497,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2.jpg","1536x1536-width":1030,"1536x1536-height":500,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2.jpg","2048x2048-width":1030,"2048x2048-height":500,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2.jpg","header-thumb-width":1030,"header-thumb-height":500,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-860x480.jpg","section-thumb-width":860,"section-thumb-height":480,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-390x315.jpg","news-thumb-width":390,"news-thumb-height":315,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-2-80x80.jpg","wpcf7-post-image-width":80,"wpcf7-post-image-height":80}},{"ID":603434,"id":603434,"title":"ATLAS AE_L new implement in BEDNAR portfolio (3)","filename":"atlas-ae_l-new-implement-in-bednar-portfolio-3.jpg","filesize":96125,"url":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3.jpg","link":"https:\/\/www.bednar.com\/fr\/blog\/atlas-ae_l-une-nouveaute-parmi-les-dechaumeurs-a-disques-bednar\/atlas-ae_l-new-implement-in-bednar-portfolio-3-2\/","alt":"","author":"14","description":"","caption":"","name":"atlas-ae_l-new-implement-in-bednar-portfolio-3-2","status":"inherit","uploaded_to":603465,"date":"2025-03-26 13:42:01","modified":"2025-03-26 13:43:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.bednar.com\/wp-includes\/images\/media\/default.png","width":1030,"height":500,"sizes":{"thumbnail":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-280x185.jpg","thumbnail-width":280,"thumbnail-height":185,"medium":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-768x373.jpg","medium_large-width":768,"medium_large-height":373,"large":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-1024x497.jpg","large-width":1024,"large-height":497,"1536x1536":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3.jpg","1536x1536-width":1030,"1536x1536-height":500,"2048x2048":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3.jpg","2048x2048-width":1030,"2048x2048-height":500,"header-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3.jpg","header-thumb-width":1030,"header-thumb-height":500,"section-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-860x480.jpg","section-thumb-width":860,"section-thumb-height":480,"news-thumb":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-390x315.jpg","news-thumb-width":390,"news-thumb-height":315,"wpcf7-post-image":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2025\/all\/atlas-ae_l-new-implement-in-bednar-portfolio-3-80x80.jpg","wpcf7-post-image-width":80,"wpcf7-post-image-height":80}}]}],"nav-main-cat":false,"nav-main-cat_kop\u00edrovat":false,"nav-sub-cat":false,"_aviaLayoutBuilderCleanData":"","page-type":"other","pageGroup":"","post-new-website":true},"_links":{"self":[{"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/posts\/603465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/comments?post=603465"}],"version-history":[{"count":3,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/posts\/603465\/revisions"}],"predecessor-version":[{"id":604993,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/posts\/603465\/revisions\/604993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/media\/603398"}],"wp:attachment":[{"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/media?parent=603465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/categories?post=603465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bednar.com\/fr\/wp-json\/wp\/v2\/tags?post=603465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}