{"id":585265,"date":"2024-11-01T15:27:24","date_gmt":"2024-11-01T14:27:24","guid":{"rendered":"https:\/\/www.bednar.com\/de\/blog\/vertrauen-sie-auf-original-ersatzteile-von-bednar\/"},"modified":"2024-11-01T15:27:24","modified_gmt":"2024-11-01T14:27:24","slug":"vertrauen-sie-auf-original-ersatzteile-von-bednar","status":"publish","type":"post","link":"https:\/\/www.bednar.com\/de\/blog\/vertrauen-sie-auf-original-ersatzteile-von-bednar\/","title":{"rendered":"Vertrauen Sie auf Original-Ersatzteile von BEDNAR"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Im Landwirtschaftsbetrieb Gospodarstwo Rolne Maciej Sik in Polen wird der Universalgrubber FENIX FO 8004 PROFI in Verbindung mit einem 540 PS starken JOHN DEERE Traktor eingesetzt. Die durchschnittliche Arbeitstiefe betr\u00e4gt 28 cm, und das Ger\u00e4t erreicht eine Arbeitsgeschwindigkeit von etwa 11 km\/h. Es handelt sich um den n\u00e4chsten BEDNAR Grubber des Unternehmens, nachdem zuvor die vorherige Generation der FENIX FO Maschine zum Einsatz kam.<\/p>\n","protected":false},"author":14,"featured_media":584186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1715,80,281,533,535,821,1003,1250,1614,1629],"tags":[],"class_list":["post-585265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fenix-fo_profi-de","category-unkategorisiert","category-fenix-fo-de","category-fenix-fn_l-de","category-fenix_fn-de","category-von-uns","category-versatill-vn_l-de","category-versatill-vo_profi-de","category-versatill-vo_l-de","category-agronomicke-en-de"],"acf":{"item-bg":false,"item-bg_kop\u00edrovat":false,"item-bg-mobile":false,"item-youtube":"","item-title":"","fixed-title":"","item-desc":"","item-mach-desc":"","item-mach-config":"","item-mach-down":"","item-align":false,"item-code":"","google-map":"","disable-header":false,"main-content":[{"acf_fc_layout":"section-news-cols","item-cols":[{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2024\/cz\/1030x500-4.jpg","item-content":"<p>Der Landwirtschaftsbetrieb Gospodarstwo Rolne Maciej Sik verwendet seit 2016 Maschinen von BEDNAR<\/p>\n","item-photo-align":false,"item-content-color":false}]},{"acf_fc_layout":"section-news-title","item-title":"","item-content":"<p>Aber es geht nicht nur um die Qualit\u00e4t der Maschine selbst, sondern vor allem um die Verschlei\u00dfteile \u2013 die Mei\u00dfel. Das Unternehmen hat ihre Maschine mit originalen und nicht-originalen Mei\u00dfeln getestet. Lesen Sie, was dabei herausgekommen ist.<\/p>\n"},{"acf_fc_layout":"section-news-title","item-title":"Testen, vergleichen und den Unterschied sehen","item-content":"<p>Nach der Bearbeitung von 300 Hektar hat sich gezeigt, dass die originalen 40-mm-LONG-LIFE-Mei\u00dfel von BEDNAR mit Hartmetallsegmenten im Vergleich zu alternativen Ersatzmei\u00dfeln, die ebenfalls Hartmetall enthalten, deutlich weniger Verschlei\u00df aufweisen. Wie die beigef\u00fcgten Fotos eindeutig best\u00e4tigen, haben die Original-BEDNAR-Mei\u00dfel ihre hohe Haltbarkeit und l\u00e4ngere Lebensdauer im Vergleich zu Ersatzteilen (Nachbauteilen) bewiesen.<\/p>\n"},{"acf_fc_layout":"section-news-cols","item-cols":[{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2024\/cz\/image-20241004-052930-1.png","item-content":"<p>Original-Mei\u00dfel BEDNAR 40 mm LONG LIFE nach 300 ha Arbeit<\/p>\n","item-photo-align":false,"item-content-color":false},{"item-title":"","item-title-h":"h3","item-photo":"https:\/\/www.bednar.com\/wp-content\/uploads\/aktuality\/2024\/cz\/image-20241004-053019-1.png","item-content":"<p>Alternative Nachbauteile \u2013 sichtbarer Unterschied im Mei\u00dfelverschlei\u00df nach 300 ha<\/p>\n","item-photo-align":false,"item-content-color":false}]},{"acf_fc_layout":"section-news-title","item-title":"","item-content":"<p>Dieser einfache Test best\u00e4tigt eindeutig, dass Original-Ersatz- und Verschlei\u00dfteile von BEDNAR die Lebensdauer der Maschine verl\u00e4ngern, einen h\u00e4ufigen Austausch besch\u00e4digter Teile reduzieren und vor allem eine konstante Arbeitsqualit\u00e4t gew\u00e4hrleisten. Original- und Nachbauteile sehen oft \u00e4hnlich aus, aber der Verschlei\u00df nach Hunderten von Hektar Arbeit kann zu erh\u00f6hten Kosten f\u00fcr den Austausch und die Wartung von Maschinen f\u00fchren.<\/p>\n<p style=\"text-align: center;\"><strong>In Anbetracht dieses Tests empfehlen wir Ihnen daher, in Originalteile zu investieren, die vom Maschinenhersteller vorgeschrieben sind, wenn Sie eine langfristige Effizienz und Zuverl\u00e4ssigkeit bei der Bodenbearbeitung erzielen m\u00f6chten.<\/strong><\/p>\n"},{"acf_fc_layout":"section-news-title","item-title":"","item-content":"<p style=\"text-align: right;\">JOY OF FARMING <a href=\"mailto:marketing@bednar.com\" target=\"_blank\" rel=\"noopener\">marketing@bednar.com<\/a> BEDNAR FMT GmbH<\/p>\n"}],"nav-main-cat":false,"nav-sub-cat":false,"_aviaLayoutBuilderCleanData":"","page-type":"other","pageGroup":"","post-new-website":true},"_links":{"self":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/posts\/585265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/comments?post=585265"}],"version-history":[{"count":0,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/posts\/585265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/media\/584186"}],"wp:attachment":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/media?parent=585265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/categories?post=585265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/tags?post=585265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}