{"id":379154,"date":"2020-03-25T00:00:00","date_gmt":"2020-03-24T23:00:00","guid":{"rendered":"https:\/\/www.bednar.com\/blog\/sicherheitsmassnahmen-des-unternehmens-bednar-gegen-die-ausbreitung-der-krankheit-covid-19"},"modified":"2020-03-25T00:00:00","modified_gmt":"2020-03-24T23:00:00","slug":"sicherheitsmassnahmen-des-unternehmens-bednar-gegen-die-ausbreitung-der-krankheit-covid-19","status":"publish","type":"post","link":"https:\/\/www.bednar.com\/de\/blog\/sicherheitsmassnahmen-des-unternehmens-bednar-gegen-die-ausbreitung-der-krankheit-covid-19\/","title":{"rendered":"Sicherheitsma\u00dfnahmen des Unternehmens BEDNAR gegen die Ausbreitung der Krankheit COVID-19"},"content":{"rendered":"<div class=\"post-section\" style=\"background-image: url(https:\/\/news.bednar.com\/wp-content\/uploads\/2018\/10\/Novinky_banner-1-1030x188.jpg);\"><\/div>\n<div class=\"one-full-section\">\n\n<p><\/div><div class=\"post-section\" style=\"background-image: url();\"><\/p>\n\n<p><\/div><p class=\"awesome-textblock\"><\/p>\n<h2>Sehr geehrte Kunden, Mitarbeiter und Anh\u00e4nger der Firma BEDNAR. Wir erleben eine Zeit, die nur sehr schwer mit etwas zu vergleichen ist, was unsere Generationen erleben konnten. Die Lage ist sehr turbulent und alles entwickelt sich sehr schnell. Was gestern unm\u00f6glich schien, ist heute ein Teil unseres Lebens.<\/h2>\n<p><\/p><\/p>\n<div class=\"hr-section\"><\/div>\n<p class=\"\"><br \/>\nWir m\u00f6chten uns wenigstens in dieser Form zu den Fragen \u00e4u\u00dfern, die sich im Zusammenhang mit der globalen Pandemie und der Ausbreitung von COVID-19, verursacht durch neue Art von Coronavirus SARS-CoV-2, ergeben.<\/p>\n<p>1) Wir unterst\u00fctzen in vollem Umfang die Schritte der Regierung der Tschechischen Republik und der internationalen Gemeinschaft zur m\u00f6glichst schnellen L\u00f6sung der aktuellen Situation.<\/p>\n<p>2) Wir haben alle m\u00f6glichen Ma\u00dfnahmen ergriffen, um die Gesundheit unserer Mitarbeiter und Gesch\u00e4ftspartner zu sch\u00fctzen. Sie umfassen die folgenden Schritte:<\/p>\n<ul>\n<li>Unsere Produktions- und Entwicklungszentren arbeiten weiterhin normal, aber wir haben den Schichtbetrieb so angepasst, damit sich die Schichtarbeiter nicht begegnen.<\/li>\n<li>Wir bitten unsere Mitarbeiter, die Hygiene strikt einzuhalten. Zum H\u00e4ndewaschen nutzen wir antibakterielle Seife und Desinfektion. Am Arbeitsplatz tragen wir Mundschutz- und Atemschutzmasken.<\/li>\n<li>Die Mitarbeiter m\u00fcssen alle geplanten Gesch\u00e4ftsreisen und Gesch\u00e4ftstreffen au\u00dfer Service-Support f\u00fcr unsere Kunden absagen.<\/li>\n<li>Wenn m\u00f6glich, bleiben m\u00f6glichst viele Mitarbeiter im\u00a0Home-Office.<\/li>\n<li>Alle Massenveranstaltungen werden abgesagt. Wir empfehlen und unterst\u00fctzen die Fernkommunikationsmittel (Telefon, E-Mail, Videokonferenz usw.)<\/li>\n<li>Mitarbeiter, bei denen Krankheitssymptome (Fieber, Atemnot, Husten, erh\u00f6hte M\u00fcdigkeit, Gelenk- und Muskelschmerzen) auftreten, m\u00fcssen sich zur Beurteilung ihres Gesundheitszustandes an ihren Arzt wenden und haben keinen Zugang zum Arbeitsplatz.<\/li>\n<\/ul>\n<p>3) Diese Zeit bringt trotz aller Bem\u00fchungen unserer Mitarbeiter und Partner wahrscheinlich eine Verschlechterung unserer Standardleistungen an die Kunden. Dies kann beispielsweise den Service-Support, rechtzeitige Lieferungen von Ersatzteilen oder die Einf\u00fchrung neuer Maschinen in Betrieb betreffen. Wir entschuldigen uns f\u00fcr diese Unannehmlichkeiten und werden im Rahmen der aktuellen M\u00f6glichkeiten alles tun, um die landwirtschaftliche Prim\u00e4rproduktion zu unterst\u00fctzen.<\/p>\n<p>4) Viele unsere Lieferanten oder auch Konkurrenten haben die Produktion bereits eingestellt oder ziehen dies in Erw\u00e4gung. Firma BEDNAR will diesen Schritt nicht unternehmen, weil wir uns der sozialen Bedeutung der landwirtschaftlichen Prim\u00e4rproduktion bewusst sind. Wenn heute die Kulturpflanzen nicht angebaut werden, wird es im Sommer keine gute Ernte geben und die Probleme, die wir jetzt durchmachen, werden weiterhin vertieft.<\/p>\n<p>Jede weitere Maschine, die wir liefern, jede weitere Dienstleistung, die wir den Bauern anbieten, kann im Endeffekt sogar das weltweite Angebot und die Preise der Lebensmittel beeinflussen. Die Instabilit\u00e4t und die Knappheit in diesem Bereich w\u00fcrden sicherlich nicht zu einer raschen L\u00f6sung der gegenw\u00e4rtigen globalen Situation beitragen.<\/p>\n<p><strong>Wir m\u00f6chten uns auf diesem Wege bei allen Mitarbeitern unserer Firma f\u00fcr das disziplinierte Verhalten bei den Arbeitspflichten und die Einhaltung der pr\u00e4ventiven Gesundheitsma\u00dfnahmen bedanken. Besonderer Dank geht an die Mitarbeiter in der Produktion f\u00fcr die Aufrechterhaltung des kontinuierlichen Produktionsprozesses.<\/strong><br \/>\n<\/p>\n<div class=\"hr-section\"><\/div>\n<p class=\"\"><\/p>\n<p style=\"text-align: right;\">Ladislav Bedn\u00e1\u0159, Gesch\u00e4ftsf\u00fchrer<br \/>\nBEDNAR FMT s.r.o.<\/p>\n<p style=\"text-align: right;\"><strong>F\u00fcr die Gesch\u00e4ftsf\u00fchrung von BEDNAR FMT s.r.o.<\/strong><\/p>\n<p><\/p>\n<div class=\"hr-section\"><\/div>\n\n<p class=\"\"><br \/>\n<br \/>\n<\/p>\n\n<div class=\"hr-section\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sehr geehrte Kunden, Mitarbeiter und Anh\u00e4nger der Firma BEDNAR. Wir erleben eine Zeit, die nur sehr schwer mit etwas zu vergleichen ist, was unsere Generationen erleben konnten. Die Lage ist sehr turbulent und alles entwickelt sich sehr schnell. Was gestern unm\u00f6glich schien, ist heute ein Teil unseres Lebens.<\/p>\n","protected":false},"author":1,"featured_media":346303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80,360],"tags":[],"class_list":["post-379154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","category-pressemeldungen"],"acf":{"item-bg":false,"item-bg_kop\u00edrovat":false,"item-bg-mobile":false,"item-youtube":"","item-title":"","fixed-title":"","item-desc":"","item-mach-desc":"","item-mach-config":"","item-mach-down":"","item-align":false,"item-code":"","google-map":"","disable-header":false,"main-content":false,"nav-main-cat":false,"nav-sub-cat":false,"_aviaLayoutBuilderCleanData":"[av_section min_height='custom' min_height_px='250px' padding='no-padding' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' custom_margin='0px' custom_margin_sync='true' custom_arrow_bg='' id='' color='main_color' background='bg_color' custom_bg='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='http:\/\/news.bednar.com\/wp-content\/uploads\/2018\/10\/Novinky_banner-1-1030x188.jpg' attachment='37463' attachment_size='large' attach='scroll' position='top center' repeat='stretch' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' av_element_hidden_in_editor='0' av_uid='av-joua11hu' custom_class=''][\/av_section]\n\n[av_one_full first min_height='av-equal-height-column' vertical_alignment='av-align-middle' space='' margin='0px' margin_sync='true' link='' linktarget='' link_hover='' padding='0px' padding_sync='true' border='' border_color='' radius='0px' radius_sync='true' background='bg_color' background_color='' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' attachment='' attachment_size='' background_position='top left' background_repeat='no-repeat' animation='' mobile_breaking='' mobile_display='' av_uid='av-jnpqbee2' custom_class='heading-top']\n\n[av_heading heading='NEUIGKEITEN' tag='h1' link_apply='' link='manually,http:\/\/' link_target='' style='blockquote modern-quote' size='28' subheading_active='' subheading_size='15' margin='' margin_sync='true' padding='0' color='' custom_font='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-k874w1a4' custom_class='' admin_preview_bg=''][\/av_heading]\n\n[\/av_one_full][av_section min_height='' min_height_px='500px' padding='small' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' custom_arrow_bg='' id='' color='main_color' background='bg_color' custom_bg='#f2f2f2' background_gradient_color1='' background_gradient_color2='' background_gradient_direction='vertical' src='' attachment='' attachment_size='' attach='scroll' position='top left' repeat='no-repeat' video='' video_ratio='16:9' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' av_element_hidden_in_editor='0' av_uid='av-jnpucduy' custom_class='']\n\n[av_heading heading='Sicherheitsma\u00dfnahmen des Unternehmens BEDNAR gegen die Ausbreitung der Krankheit COVID-19' tag='h1' link_apply='' link='manually,http:\/\/' link_target='' style='blockquote modern-quote' size='24' subheading_active='' subheading_size='15' margin='' margin_sync='true' padding='0' color='' custom_font='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-k874w72y' custom_class='' admin_preview_bg=''][\/av_heading]\n\n[\/av_section][av_textblock size='' font_color='' color='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-7st7' custom_class='awesome-textblock' admin_preview_bg='']\n<h2>Sehr geehrte Kunden, Mitarbeiter und Anh\u00e4nger der Firma BEDNAR. Wir erleben eine Zeit, die nur sehr schwer mit etwas zu vergleichen ist, was unsere Generationen erleben konnten. Die Lage ist sehr turbulent und alles entwickelt sich sehr schnell. Was gestern unm\u00f6glich schien, ist heute ein Teil unseres Lebens.<\/h2>\n[\/av_textblock]\n\n[av_hr class='invisible' height='20' shadow='no-shadow' position='center' custom_border='av-border-thin' custom_width='50px' custom_border_color='' custom_margin_top='30px' custom_margin_bottom='30px' icon_select='yes' custom_icon_color='' icon='ue808' font='entypo-fontello' av_uid='av-jnppiwll' custom_class='' admin_preview_bg='']\n\n[av_textblock size='' font_color='' color='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-jiadqhq3' custom_class='' admin_preview_bg='']\nWir m\u00f6chten uns wenigstens in dieser Form zu den Fragen \u00e4u\u00dfern, die sich im Zusammenhang mit der globalen Pandemie und der Ausbreitung von COVID-19, verursacht durch neue Art von Coronavirus SARS-CoV-2, ergeben.\n\n1) Wir unterst\u00fctzen in vollem Umfang die Schritte der Regierung der Tschechischen Republik und der internationalen Gemeinschaft zur m\u00f6glichst schnellen L\u00f6sung der aktuellen Situation.\n\n2) Wir haben alle m\u00f6glichen Ma\u00dfnahmen ergriffen, um die Gesundheit unserer Mitarbeiter und Gesch\u00e4ftspartner zu sch\u00fctzen. Sie umfassen die folgenden Schritte:\n<ul>\n \t<li>Unsere Produktions- und Entwicklungszentren arbeiten weiterhin normal, aber wir haben den Schichtbetrieb so angepasst, damit sich die Schichtarbeiter nicht begegnen.<\/li>\n \t<li>Wir bitten unsere Mitarbeiter, die Hygiene strikt einzuhalten. Zum H\u00e4ndewaschen nutzen wir antibakterielle Seife und Desinfektion. Am Arbeitsplatz tragen wir Mundschutz- und Atemschutzmasken.<\/li>\n \t<li>Die Mitarbeiter m\u00fcssen alle geplanten Gesch\u00e4ftsreisen und Gesch\u00e4ftstreffen au\u00dfer Service-Support f\u00fcr unsere Kunden absagen.<\/li>\n \t<li>Wenn m\u00f6glich, bleiben m\u00f6glichst viele Mitarbeiter im\u00a0Home-Office.<\/li>\n \t<li>Alle Massenveranstaltungen werden abgesagt. Wir empfehlen und unterst\u00fctzen die Fernkommunikationsmittel (Telefon, E-Mail, Videokonferenz usw.)<\/li>\n \t<li>Mitarbeiter, bei denen Krankheitssymptome (Fieber, Atemnot, Husten, erh\u00f6hte M\u00fcdigkeit, Gelenk- und Muskelschmerzen) auftreten, m\u00fcssen sich zur Beurteilung ihres Gesundheitszustandes an ihren Arzt wenden und haben keinen Zugang zum Arbeitsplatz.<\/li>\n<\/ul>\n3) Diese Zeit bringt trotz aller Bem\u00fchungen unserer Mitarbeiter und Partner wahrscheinlich eine Verschlechterung unserer Standardleistungen an die Kunden. Dies kann beispielsweise den Service-Support, rechtzeitige Lieferungen von Ersatzteilen oder die Einf\u00fchrung neuer Maschinen in Betrieb betreffen. Wir entschuldigen uns f\u00fcr diese Unannehmlichkeiten und werden im Rahmen der aktuellen M\u00f6glichkeiten alles tun, um die landwirtschaftliche Prim\u00e4rproduktion zu unterst\u00fctzen.\n\n4) Viele unsere Lieferanten oder auch Konkurrenten haben die Produktion bereits eingestellt oder ziehen dies in Erw\u00e4gung. Firma BEDNAR will diesen Schritt nicht unternehmen, weil wir uns der sozialen Bedeutung der landwirtschaftlichen Prim\u00e4rproduktion bewusst sind. Wenn heute die Kulturpflanzen nicht angebaut werden, wird es im Sommer keine gute Ernte geben und die Probleme, die wir jetzt durchmachen, werden weiterhin vertieft.\n\nJede weitere Maschine, die wir liefern, jede weitere Dienstleistung, die wir den Bauern anbieten, kann im Endeffekt sogar das weltweite Angebot und die Preise der Lebensmittel beeinflussen. Die Instabilit\u00e4t und die Knappheit in diesem Bereich w\u00fcrden sicherlich nicht zu einer raschen L\u00f6sung der gegenw\u00e4rtigen globalen Situation beitragen.\n\n<strong>Wir m\u00f6chten uns auf diesem Wege bei allen Mitarbeitern unserer Firma f\u00fcr das disziplinierte Verhalten bei den Arbeitspflichten und die Einhaltung der pr\u00e4ventiven Gesundheitsma\u00dfnahmen bedanken. Besonderer Dank geht an die Mitarbeiter in der Produktion f\u00fcr die Aufrechterhaltung des kontinuierlichen Produktionsprozesses.<\/strong>\n[\/av_textblock]\n\n[av_hr class='invisible' height='20' shadow='no-shadow' position='center' custom_border='av-border-thin' custom_width='50px' custom_border_color='' custom_margin_top='30px' custom_margin_bottom='30px' icon_select='yes' custom_icon_color='' icon='ue808' font='entypo-fontello' av_uid='av-jnppiwll' custom_class='' admin_preview_bg='']\n\n[av_textblock size='' font_color='' color='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-jiaegma5' custom_class='' admin_preview_bg='']\n<p style=\"text-align: right;\">Ladislav Bedn\u00e1\u0159, Gesch\u00e4ftsf\u00fchrer\nBEDNAR FMT s.r.o.<\/p>\n<p style=\"text-align: right;\"><strong>F\u00fcr die Gesch\u00e4ftsf\u00fchrung von BEDNAR FMT s.r.o.<\/strong><\/p>\n[\/av_textblock]\n\n[av_hr class='invisible' height='20' shadow='no-shadow' position='center' custom_border='av-border-thin' custom_width='50px' custom_border_color='' custom_margin_top='30px' custom_margin_bottom='30px' icon_select='yes' custom_icon_color='' icon='ue808' font='entypo-fontello' av_uid='av-jiaei1fo' custom_class='' admin_preview_bg='']\n\n[av_heading heading='NEUIGKEITEN' tag='h2' link_apply='' link='manually,http:\/\/' link_target='' style='' size='' subheading_active='' subheading_size='15' margin='' margin_sync='true' padding='10' color='' custom_font='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-k874xtx2' custom_class='' admin_preview_bg=''][\/av_heading]\n\n[av_textblock size='' font_color='' color='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' av_uid='av-joua318z' custom_class='' admin_preview_bg='']\n[bednar_news id1=285097 id2=284692 id3=282343][\/bednar_news]\n[\/av_textblock]\n\n[av_button label='<span style=\"font-size: large;\">Mehr Neuigkeiten <\/span>' link='page,36878' link_target='' size='large' position='center' label_display='' icon_select='yes' icon_hover='aviaTBicon_hover' icon='ue811' font='entypo-fontello' color='custom' custom_bg='#feff00' custom_font='#2d2d2d' av_uid='av-joh7foel' custom_class='' admin_preview_bg='']\n\n[av_hr av_uid='av-2vfycv']","page-type":"","pageGroup":"","post-new-website":false},"_links":{"self":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/posts\/379154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/comments?post=379154"}],"version-history":[{"count":0,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/posts\/379154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/media\/346303"}],"wp:attachment":[{"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/media?parent=379154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/categories?post=379154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bednar.com\/de\/wp-json\/wp\/v2\/tags?post=379154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}